{"id":11740,"date":"2026-05-29T07:44:55","date_gmt":"2026-05-29T10:44:55","guid":{"rendered":"https:\/\/cauim.org\/?p=11740"},"modified":"2026-07-01T18:37:30","modified_gmt":"2026-07-01T21:37:30","slug":"cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos","status":"publish","type":"post","link":"https:\/\/cauim.org\/es\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/","title":{"rendered":"CAUIM EXHIBE, EN EL PROYECTO &quot;EL MUNDO EN EL CINE&quot;, PEL\u00cdCULAS RELACIONADAS CON LOS DERECHOS HUMANOS."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11740\" class=\"elementor elementor-11740\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a1d64d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a1d64d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2511e35a\" data-id=\"2511e35a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43999fa6 elementor-widget elementor-widget-text-editor\" data-id=\"43999fa6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>ACUERDO DE FINANCIACI\u00d3N N.\u00ba 301\/2026<em><br \/><\/em>P<\/strong><strong>PROCESO SCEC-PRC-2026-00076-DM<em><br \/><\/em>D<\/strong><strong>emanda 100590<em><br \/><\/em>U<\/strong><strong>GE\u00a0120125<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>En el segundo p\u00e1rrafo del prefacio de su libro <em>El cine: su arte, su t\u00e9cnica, su econom\u00eda.<\/em> (<em>Le Cin\u00e9ma Son Art, Sa Tecnique, Son \u00c9conomie<\/em>, traducido por Luiz &amp; Thais L. de Vasconcelos, con la colaboraci\u00f3n de Adriano Kury, R\u00edo de Janeiro, Livraria-Editora da Casa do Estudante do Brasil, 1951, p. 9), el cr\u00edtico e historiador de cine franc\u00e9s Georges Sadoul (1904-1967) escribi\u00f3:<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>\u201cEl cine es, ante todo, entretenimiento. Pero tambi\u00e9n es, sin que siempre seamos conscientes de ello, un medio de instrucci\u00f3n. A trav\u00e9s de las pel\u00edculas, sin salir del peque\u00f1o pueblo o aldea donde viven, el espectador aprende sobre pa\u00edses lejanos, entra en contacto con sus costumbres, sus paisajes, sus viviendas, su civilizaci\u00f3n. El cine, al mostrar, hace que las cosas se conozcan m\u00e1s f\u00e1cilmente que los libros y los escritos. Los escritores describen las olas del mar. Las pel\u00edculas nos las hacen ver en toda su impresionante veracidad.\u201d<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Reflexionando sobre las palabras de Sadoul, llegamos a la conclusi\u00f3n de que el cine es la m\u00e1quina del tiempo y el dispositivo de teletransportaci\u00f3n m\u00e1s accesibles jam\u00e1s creados. Porque, a menudo, vemos una pel\u00edcula despreocupadamente, buscando solo entretenimiento, y, sin darnos cuenta, recibimos un pasaporte sellado a un rinc\u00f3n diferente del mundo.<em><br \/><\/em>Viajar f\u00edsicamente es una experiencia incre\u00edble e inolvidable. Sin embargo, solo podemos llegar hasta donde nos lo permitan el mapa y nuestro presupuesto. El cine ya no tiene estas barreras. Nos lleva a un Nueva York futurista, al desierto del Sahara, a las calles hist\u00f3ricas de Roma, al coraz\u00f3n de \u00c1frica, a la Antigua Grecia, a un pueblo en la campi\u00f1a brasile\u00f1a\u2026<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>M<\/strong><strong>Pero la gran magia del cine no reside solo en mostrar paisajes. Reside en mostrar el alma de un pueblo.<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Quando assistimos a um filme produzido em outro pa\u00eds, n\u00f3s n\u00e3o estamos apenas vendo pontos tur\u00edsticos. N\u00f3s estamos observando como os habitantes daquele pa\u00eds tomam caf\u00e9 da manh\u00e3, como eles lidam com o luto, o que faz eles sorrirem, quais s\u00e3o os seus maiores medos&#8230; Enfim, aprendemos, de forma viva e pulsante, sobre os costumes, as tradi\u00e7\u00f5es e a Hist\u00f3ria daquele pa\u00eds.<em><br \/><\/em>E, entre 1\u00ba de junho de 2025 e 30 de junho de 2026, nas sess\u00f5es <strong>El mundo en el cine<\/strong>, o Cauim, o cineclube que difunde cidadania e cultura em Ribeir\u00e3o Preto, ir\u00e1 exibir uma s\u00e9rie de filmes relacionados aos direitos humanos.<em><br \/><\/em>Ent\u00e3o, embarque no Cauim e aproveite estas sess\u00f5es.<em><br \/><\/em>A seguir, a <strong>Programa\u00e7\u00e3o<\/strong> completa.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>PROGRAMA\u00c7\u00c3O DOS DIAS 06\/06\/2026 E 07\/06\/2026<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>06\/06\/2026 \u2013 14 horas<em><br \/>Y<\/em><\/strong><strong><em>\u00f5g \u00c3tak: Meu Pai, Kaiow\u00e1<\/em><\/strong> (2024, 90\u2019)<em><br \/><\/em><strong><em>Y\u00f5g \u00c3tak: Meu Pai, Kaiow\u00e1<\/em><\/strong> conta a busca de Sueli Maxakali e Ma\u00edsa Maxakali pelo pai, Luis Kaiow\u00e1, de quem foram separadas durante a ditadura militar no Brasil. O filme acompanha a jornada da cineasta para reencontrar o pai, bem como as lutas enfrentadas pelos povos ind\u00edgenas Tikm\u0169\u2019\u0169n e Kaiow\u00e1 em defesa de seus territ\u00f3rios e modos de vida.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Sueli Maxakali, Isael Maxakali, Roberto Romero &amp; Luisa Lanna<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa livre.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:image {\"id\":11742,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"535\" class=\"wp-image-11742\" src=\"https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/1-5-1024x535.jpg\" alt=\"\" srcset=\"https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/1-5-1024x535.jpg 1024w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/1-5-300x157.jpg 300w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/1-5-768x401.jpg 768w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/1-5-18x9.jpg 18w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/1-5-650x339.jpg 650w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/1-5.jpg 1130w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<p><!-- \/wp:image --><!-- wp:paragraph --><\/p>\n<p><strong>07\/06\/2026 \u2013 14 horas<em><br \/>Y<\/em><\/strong><strong><em>\u00f5g \u00c3tak: Meu Pai, Kaiow\u00e1<\/em><\/strong> (2024, 90\u2019)<em><br \/><\/em><strong><em>Y\u00f5g \u00c3tak: Meu Pai, Kaiow\u00e1<\/em><\/strong> conta a busca de Sueli Maxakali e Ma\u00edsa Maxakali pelo pai, Luis Kaiow\u00e1, de quem foram separadas durante a ditadura militar no Brasil. O filme acompanha a jornada da cineasta para reencontrar o pai, bem como as lutas enfrentadas pelos povos ind\u00edgenas Tikm\u0169\u2019\u0169n e Kaiow\u00e1 em defesa de seus territ\u00f3rios e modos de vida.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Sueli Maxakali, Isael Maxakali, Roberto Romero &amp; Luisa Lanna<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa livre.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>PROGRAMA\u00c7\u00c3O DOS DIAS 13\/06\/2026 E 14\/06\/2026<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>13\/06\/2026 \u2013 14 horas<em><br \/>C<\/em><\/strong><strong><em>errado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> (2025, 17\u2019)<em><br \/><\/em><strong>C<em>errado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> transporta o espectador por uma viagem pelas \u00e1guas que ligam o Cerrado \u00e0 Amaz\u00f4nia, \u00e0 Caatinga e ao Pantanal, desde a nascente at\u00e9 o encontro com grandes rios. A partir dos relatos de povos ind\u00edgenas e de povos e comunidades tradicionais, destacam-se as amea\u00e7as e a destrui\u00e7\u00e3o do meio ambiente e dos modos de vida que protegem a Natureza.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Fellipe Abreu &amp; Luis Felipe Silva<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa livre.<em><br \/><strong>As Lavadeiras do Rio Acara\u00fa Transformam a Embarca\u00e7\u00e3o em Nave de Condu\u00e7\u00e3o <\/strong><\/em>(2021, 12\u2019)<em><br \/><\/em>O fluxo das \u00e1guas do Rio Acara\u00fa, que atravessa a cidade de Sobral, no Cear\u00e1, conta uma hist\u00f3ria na qual o esfregar e o voar fazem parte do mesmo gesto coletivo.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Kulumym-A\u00e7u<em><br \/><\/em>Este document\u00e1rio\/experimental tem classifica\u00e7\u00e3o livre.<em><br \/><\/em><strong><em>Kutala<\/em><\/strong> (2025, 5\u2019)<em><br \/><\/em>As brincadeiras de crian\u00e7as de terreiro do Kilombu Manzo, na observ\u00e2ncia dos mais velhos, transmitem o saber ancestral \u00e0 gera\u00e7\u00e3o neta, em que passado, presente e futuro se entrela\u00e7am, demostrando que o saber quilombola est\u00e1 plantado nas matas e corre livre nos caminhos das \u00e1guas, fazendo-nos confundir a interpreta\u00e7\u00e3o do ontem no tempo do hoje.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Fabio Martins &amp; Quilombo Manzo<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa de 12 anos.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:image {\"id\":11743,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"461\" class=\"wp-image-11743\" src=\"https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/3-5-1024x461.jpg\" alt=\"\" srcset=\"https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/3-5-1024x461.jpg 1024w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/3-5-300x135.jpg 300w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/3-5-768x346.jpg 768w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/3-5-18x8.jpg 18w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/3-5-650x293.jpg 650w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/3-5.jpg 1299w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<p><!-- \/wp:image --><!-- wp:paragraph --><\/p>\n<p><em>Uma imagem do filme<\/em> Kutala<em>.<\/em><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>14\/06\/2026 \u2013 14 horas<em><br \/>C<\/em><\/strong><strong><em>errado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> (2025, 17\u2019)<em><br \/><strong>C<\/strong><\/em><strong><em>errado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> transporta o espectador por uma viagem pelas \u00e1guas que ligam o Cerrado \u00e0 Amaz\u00f4nia, \u00e0 Caatinga e ao Pantanal, desde a nascente at\u00e9 o encontro com grandes rios. A partir dos relatos de povos ind\u00edgenas e de povos e comunidades tradicionais, destacam-se as amea\u00e7as e a destrui\u00e7\u00e3o do meio ambiente e dos modos de vida que protegem a Natureza.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Fellipe Abreu &amp; Luis Felipe Silva<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa livre.<em><br \/><\/em><strong><em>As Lavadeiras do Rio Acara\u00fa Transformam a Embarca\u00e7\u00e3o em Nave de Condu\u00e7\u00e3<\/em><\/strong><em><strong>o<\/strong><\/em>(2021, 12\u2019)<em><br \/><\/em>O fluxo das \u00e1guas do Rio Acara\u00fa, que atravessa a cidade de Sobral, no Cear\u00e1, conta uma hist\u00f3ria na qual o esfregar e o voar fazem parte do mesmo gesto coletivo.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Kulumym-A\u00e7u<em><br \/><\/em>Este document\u00e1rio\/experimental tem classifica\u00e7\u00e3o livre.<em><br \/><\/em><strong><em>Kutala<\/em><\/strong> (2025, 5\u2019)<em><br \/><\/em>As brincadeiras de crian\u00e7as de terreiro do Kilombu Manzo, na observ\u00e2ncia dos mais velhos, transmitem o saber ancestral \u00e0 gera\u00e7\u00e3o neta, em que passado, presente e futuro se entrela\u00e7am, demostrando que o saber quilombola est\u00e1 plantado nas matas e corre livre nos caminhos das \u00e1guas, fazendo-nos confundir a interpreta\u00e7\u00e3o do ontem no tempo do hoje.<em><br \/><\/em><strong>Direcci\u00f3n:<\/strong> Fabio Martins &amp; Quilombo Manzo<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa de 12 anos.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>PROGRAMA\u00c7\u00c3O DOS DIAS 27\/06\/2026 E 28\/06\/2026<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>27\/06\/2026 \u2013 14 horas<em><br \/>C<\/em><\/strong><strong><em>errado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> (2025, 17\u2019)<em><br \/><\/em><strong><em>Cerrado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> transporta o espectador por uma viagem pelas \u00e1guas que ligam o Cerrado \u00e0 Amaz\u00f4nia, \u00e0 Caatinga e ao Pantanal, desde a nascente at\u00e9 o encontro com grandes rios. A partir dos relatos de povos ind\u00edgenas e de povos e comunidades tradicionais, destacam-se as amea\u00e7as e a destrui\u00e7\u00e3o do meio ambiente e dos modos de vida que protegem a Natureza.<em><br \/><\/em><strong>Di<\/strong><strong>re\u00e7\u00e3o:<\/strong> Fellipe Abreu &amp; Luis Felipe Silva<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa livre.<em><br \/><strong>A<\/strong><\/em><strong><em>s Lavadeiras do Rio Acara\u00fa Transformam a Embarca\u00e7\u00e3o em Nave de Condu\u00e7\u00e3o <\/em><\/strong>(2021, 12\u2019)<em><br \/><\/em>O fluxo das \u00e1guas do Rio Acara\u00fa, que atravessa a cidade de Sobral, no Cear\u00e1, conta uma hist\u00f3ria na qual o esfregar e o voar fazem parte do mesmo gesto coletivo.<em><br \/><\/em><strong>D<\/strong><strong>direcci\u00f3n:<\/strong> Kulumym-A\u00e7u<em><br \/><\/em>Este document\u00e1rio\/experimental tem classifica\u00e7\u00e3o livre.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:image {\"id\":11745,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"614\" class=\"wp-image-11745\" src=\"https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-1024x614.jpg\" alt=\"\" srcset=\"https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-1024x614.jpg 1024w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-300x180.jpg 300w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-768x461.jpg 768w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-1536x922.jpg 1536w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-18x12.jpg 18w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-650x390.jpg 650w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4-1320x792.jpg 1320w, https:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/4-4.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<p><!-- \/wp:image --><!-- wp:paragraph --><\/p>\n<p><strong><em>Kutala<\/em><\/strong> (2025, 5\u2019)<em><br \/><\/em>As brincadeiras de crian\u00e7as de terreiro do Kilombu Manzo, na observ\u00e2ncia dos mais velhos, transmitem o saber ancestral \u00e0 gera\u00e7\u00e3o neta, em que passado, presente e futuro se entrela\u00e7am, demostrando que o saber quilombola est\u00e1 plantado nas matas e corre livre nos caminhos das \u00e1guas, fazendo-nos confundir a interpreta\u00e7\u00e3o do ontem no tempo do hoje.<em><br \/><\/em><strong>D<\/strong><strong>direcci\u00f3n:<\/strong> Fabio Martins &amp; Quilombo Manzo<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa de 12 anos.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>28\/06\/2026 \u2013 14 horas<em><br \/>C<\/em><\/strong><strong><em>errado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> (2025, 17\u2019)<em><br \/><strong>C<\/strong><\/em><strong><em>errado, Cora\u00e7\u00e3o das \u00c1guas: Conex\u00e3o Caatinga<\/em><\/strong> transporta o espectador por uma viagem pelas \u00e1guas que ligam o Cerrado \u00e0 Amaz\u00f4nia, \u00e0 Caatinga e ao Pantanal, desde a nascente at\u00e9 o encontro com grandes rios. A partir dos relatos de povos ind\u00edgenas e de povos e comunidades tradicionais, destacam-se as amea\u00e7as e a destrui\u00e7\u00e3o do meio ambiente e dos modos de vida que protegem a Natureza.<em><br \/><\/em><strong>D<\/strong><strong>direcci\u00f3n:<\/strong> Fellipe Abreu &amp; Luis Felipe Silva<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa livre.<em><br \/><strong>A<\/strong><strong>s Lavadeiras do Rio Acara\u00fa Transformam a Embarca\u00e7\u00e3o em Nave de Condu\u00e7\u00e3o <\/strong><\/em>(2021, 12\u2019)<em><br \/><\/em>O fluxo das \u00e1guas do Rio Acara\u00fa, que atravessa a cidade de Sobral, no Cear\u00e1, conta uma hist\u00f3ria na qual o esfregar e o voar fazem parte do mesmo gesto coletivo.<em><br \/><\/em><strong>D<\/strong><strong>direcci\u00f3n:<\/strong> Kulumym-A\u00e7u<em><br \/><\/em>Este document\u00e1rio\/experimental tem classifica\u00e7\u00e3o livre.<em><br \/><\/em><strong><em>Kutala<\/em><\/strong> (2025, 5\u2019)<em><br \/><\/em>As brincadeiras de crian\u00e7as de terreiro do Kilombu Manzo, na observ\u00e2ncia dos mais velhos, transmitem o saber ancestral \u00e0 gera\u00e7\u00e3o neta, em que passado, presente e futuro se entrela\u00e7am, demostrando que o saber quilombola est\u00e1 plantado nas matas e corre livre nos caminhos das \u00e1guas, fazendo-nos confundir a interpreta\u00e7\u00e3o do ontem no tempo do hoje.<em><br \/><\/em><strong>D<\/strong><strong>direcci\u00f3n:<\/strong> Fabio Martins &amp; Quilombo Manzo<em><br \/><\/em>Este document\u00e1rio tem classifica\u00e7\u00e3o indicativa de 12 anos.<\/p>\n<p><b>OBSERVA\u00c7\u00c3O: EM TODAS AS SESS\u00d5ES, A ENTRADA SER\u00c1 GRATUITA.<\/b><\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>TERMO DE FOMENTO N\u00ba 301\/2026PROCESSO SCEC-PRC-2026-00076-DMDemanda 100590UGE\u00a0120125 No segundo par\u00e1grafo do Pref\u00e1cio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[60,30],"tags":[],"class_list":["post-11740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinematografo","category-projetos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS - Cine Clube Cauim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cauim.org\/es\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS - Cine Clube Cauim\" \/>\n<meta property=\"og:description\" content=\"TERMO DE FOMENTO N\u00ba 301\/2026PROCESSO SCEC-PRC-2026-00076-DMDemanda 100590UGE\u00a0120125 No segundo par\u00e1grafo do Pref\u00e1cio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cauim.org\/es\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Cine Clube Cauim\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T10:44:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T21:37:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/capa-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marcoal.lucchetti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"marcoal.lucchetti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/\"},\"author\":{\"name\":\"marcoal.lucchetti\",\"@id\":\"https:\/\/cauim.org\/#\/schema\/person\/3f1c3cdcd0cfeb72cea8b62c3585a4dc\"},\"headline\":\"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS\",\"datePublished\":\"2026-05-29T10:44:55+00:00\",\"dateModified\":\"2026-07-01T21:37:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/\"},\"wordCount\":1601,\"publisher\":{\"@id\":\"https:\/\/cauim.org\/#organization\"},\"articleSection\":[\"Cinemat\u00f3grafo\",\"Projetos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/\",\"url\":\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/\",\"name\":\"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS - Cine Clube Cauim\",\"isPartOf\":{\"@id\":\"https:\/\/cauim.org\/#website\"},\"datePublished\":\"2026-05-29T10:44:55+00:00\",\"dateModified\":\"2026-07-01T21:37:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/cauim.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cauim.org\/#website\",\"url\":\"https:\/\/cauim.org\/\",\"name\":\"Cine Clube Cauim\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cauim.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cauim.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cauim.org\/#organization\",\"name\":\"Cine Clube Cauim\",\"url\":\"https:\/\/cauim.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cauim.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cauim.org\/wp-content\/uploads\/2023\/06\/cauim-roxo.png\",\"contentUrl\":\"https:\/\/cauim.org\/wp-content\/uploads\/2023\/06\/cauim-roxo.png\",\"width\":596,\"height\":161,\"caption\":\"Cine Clube Cauim\"},\"image\":{\"@id\":\"https:\/\/cauim.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/cauimoficial\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cauim.org\/#\/schema\/person\/3f1c3cdcd0cfeb72cea8b62c3585a4dc\",\"name\":\"marcoal.lucchetti\",\"url\":\"https:\/\/cauim.org\/es\/author\/marcoal-lucchetti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS - Cine Clube Cauim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cauim.org\/es\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/","og_locale":"es_ES","og_type":"article","og_title":"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS - Cine Clube Cauim","og_description":"TERMO DE FOMENTO N\u00ba 301\/2026PROCESSO SCEC-PRC-2026-00076-DMDemanda 100590UGE\u00a0120125 No segundo par\u00e1grafo do Pref\u00e1cio [&hellip;]","og_url":"https:\/\/cauim.org\/es\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/","og_site_name":"Cine Clube Cauim","article_published_time":"2026-05-29T10:44:55+00:00","article_modified_time":"2026-07-01T21:37:30+00:00","og_image":[{"width":850,"height":476,"url":"http:\/\/cauim.org\/wp-content\/uploads\/2026\/05\/capa-4.jpg","type":"image\/jpeg"}],"author":"marcoal.lucchetti","twitter_card":"summary_large_image","twitter_misc":{"Written by":"marcoal.lucchetti","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/#article","isPartOf":{"@id":"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/"},"author":{"name":"marcoal.lucchetti","@id":"https:\/\/cauim.org\/#\/schema\/person\/3f1c3cdcd0cfeb72cea8b62c3585a4dc"},"headline":"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS","datePublished":"2026-05-29T10:44:55+00:00","dateModified":"2026-07-01T21:37:30+00:00","mainEntityOfPage":{"@id":"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/"},"wordCount":1601,"publisher":{"@id":"https:\/\/cauim.org\/#organization"},"articleSection":["Cinemat\u00f3grafo","Projetos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/","url":"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/","name":"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS - Cine Clube Cauim","isPartOf":{"@id":"https:\/\/cauim.org\/#website"},"datePublished":"2026-05-29T10:44:55+00:00","dateModified":"2026-07-01T21:37:30+00:00","breadcrumb":{"@id":"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cauim.org\/cauim-exibe-no-projeto-o-mundo-no-cinema-filmes-relacionados-aos-direitos-humanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cauim.org\/"},{"@type":"ListItem","position":2,"name":"CAUIM EXIBE, NO PROJETO O MUNDO NO CINEMA, FILMES RELACIONADOS AOS DIREITOS HUMANOS"}]},{"@type":"WebSite","@id":"https:\/\/cauim.org\/#website","url":"https:\/\/cauim.org\/","name":"Club de cine de Cauim","description":"","publisher":{"@id":"https:\/\/cauim.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cauim.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cauim.org\/#organization","name":"Club de cine de Cauim","url":"https:\/\/cauim.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cauim.org\/#\/schema\/logo\/image\/","url":"https:\/\/cauim.org\/wp-content\/uploads\/2023\/06\/cauim-roxo.png","contentUrl":"https:\/\/cauim.org\/wp-content\/uploads\/2023\/06\/cauim-roxo.png","width":596,"height":161,"caption":"Cine Clube Cauim"},"image":{"@id":"https:\/\/cauim.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/cauimoficial\/"]},{"@type":"Person","@id":"https:\/\/cauim.org\/#\/schema\/person\/3f1c3cdcd0cfeb72cea8b62c3585a4dc","name":"marcoal.lucchetti","url":"https:\/\/cauim.org\/es\/author\/marcoal-lucchetti\/"}]}},"_links":{"self":[{"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/posts\/11740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/comments?post=11740"}],"version-history":[{"count":49,"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/posts\/11740\/revisions"}],"predecessor-version":[{"id":12223,"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/posts\/11740\/revisions\/12223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/media\/11747"}],"wp:attachment":[{"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/media?parent=11740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/categories?post=11740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cauim.org\/es\/wp-json\/wp\/v2\/tags?post=11740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}